{"id":5672,"date":"2015-05-06T19:27:11","date_gmt":"2015-05-06T17:27:11","guid":{"rendered":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg"},"modified":"2015-05-06T19:27:11","modified_gmt":"2015-05-06T17:27:11","slug":"conrad-stoltz-nappy-motorcycling-elephant","status":"inherit","type":"attachment","link":"https:\/\/www.conradstoltz.com\/index.php\/life-in-the-life-of-the-caveman-xterra-new-zealand\/conrad-stoltz-nappy-motorcycling-elephant\/","title":{"rendered":"Conrad Stoltz nappy motorcycling elephant"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conrad Stoltz nappy motorcycling elephant - Conrad Stoltz XTERRA Triathlete\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Conrad Stoltz XTERRA Triathlete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/conradstoltzcom\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@ConradStoltz\" \/>\n<meta name=\"twitter:site\" content=\"@ConradStoltz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.conradstoltz.com\/#website\",\"url\":\"https:\/\/www.conradstoltz.com\/\",\"name\":\"Conrad Stoltz XTERRA Triathlete\",\"description\":\"7 x World Champion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.conradstoltz.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg#webpage\",\"url\":\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg\",\"name\":\"Conrad Stoltz nappy motorcycling elephant - Conrad Stoltz XTERRA Triathlete\",\"isPartOf\":{\"@id\":\"https:\/\/www.conradstoltz.com\/#website\"},\"datePublished\":\"2015-05-06T17:27:11+00:00\",\"dateModified\":\"2015-05-06T17:27:11+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg'><img width=\"400\" height=\"400\" src=\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-400x400.jpg 400w, https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-150x150.jpg 150w, https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg 660w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":660,"height":660,"file":"2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg","sizes":{"thumbnail":{"file":"Conrad-Stoltz-nappy-motorcycling-elephant-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-150x150.jpg"},"medium":{"file":"Conrad-Stoltz-nappy-motorcycling-elephant-400x400.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-400x400.jpg"},"post-thumbnail":{"file":"Conrad-Stoltz-nappy-motorcycling-elephant-120x100.jpg","width":120,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-120x100.jpg"},"gantryThumb":{"file":"Conrad-Stoltz-nappy-motorcycling-elephant-120x100.jpg","width":120,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant-120x100.jpg"},"full":{"file":"Conrad-Stoltz-nappy-motorcycling-elephant.jpg","width":660,"height":660,"mime_type":"image\/jpeg","source_url":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg"}},"image_meta":{"aperture":2.2,"credit":"","camera":"iPhone 5s","caption":"","created_timestamp":1428008643,"copyright":"","focal_length":"4.15","iso":"400","shutter_speed":"0.058823529411765","title":"","orientation":1}},"post":5665,"source_url":"https:\/\/www.conradstoltz.com\/wp-content\/uploads\/2015\/05\/Conrad-Stoltz-nappy-motorcycling-elephant.jpg","_links":{"self":[{"href":"https:\/\/www.conradstoltz.com\/index.php\/wp-json\/wp\/v2\/media\/5672"}],"collection":[{"href":"https:\/\/www.conradstoltz.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.conradstoltz.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.conradstoltz.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conradstoltz.com\/index.php\/wp-json\/wp\/v2\/comments?post=5672"}]}}